{"id":1796,"date":"2013-04-23T15:53:09","date_gmt":"2013-04-23T20:23:09","guid":{"rendered":"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/?p=1796"},"modified":"2013-04-24T16:24:24","modified_gmt":"2013-04-24T20:54:24","slug":"contraloria-del-estado-amazonas-dictara-taller-de-pasivos-laborales","status":"publish","type":"post","link":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/2013\/04\/contraloria-del-estado-amazonas-dictara-taller-de-pasivos-laborales\/","title":{"rendered":"Contralor\u00eda del estado Amazonas dicto taller de Pasivos Laborales"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><a href=\"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07974-Copy.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1794\" alt=\"Taller pasivos laborales\" src=\"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07974-Copy-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07974-Copy-300x199.jpg 300w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07974-Copy-1024x681.jpg 1024w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07974-Copy.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Siguiendo las directrices de la Contralor\u00eda General de la Rep\u00fablica, en la Contralor\u00eda del estado Amazonas, se dicto un taller del proceso aplicable para el c\u00e1lculo de los pasivos laborales que se les adeuden a los trabajadores y ex trabajadores, de la gobernaci\u00f3n del estado Amazonas, as\u00ed como a las alcald\u00edas, sus entes Descentralizados estadales y municipales y Unidades de Auditor\u00eda Interna.<\/h3>\n<h3 style=\"text-align: justify;\"><a href=\"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07962-Copy.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1793\" alt=\"Asistentes al Taller pasivos laborales\" src=\"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07962-Copy-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07962-Copy-300x199.jpg 300w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07962-Copy-1024x681.jpg 1024w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2013\/04\/DSC07962-Copy.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La actividad se realizo el d\u00eda de hoy 23 de Abril, en el edificio sede del ente Contralor, y fue coordinada por el licenciado Jos\u00e9 Parra funcionario de la Direcci\u00f3n de Control Posterior de la Administraci\u00f3n Estadal y la ingeniero Janeth Di Marco funcionaria adscrita a la Unidad de Planificaci\u00f3n e Inform\u00e1tica.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Siguiendo las directrices de la Contralor\u00eda General de la Rep\u00fablica, en la Contralor\u00eda del estado Amazonas, se dicto un taller del proceso aplicable para el c\u00e1lculo de los pasivos laborales que se les adeuden a los trabajadores y ex trabajadores, &hellip; <a class=\"more-link\" href=\"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/2013\/04\/contraloria-del-estado-amazonas-dictara-taller-de-pasivos-laborales\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-1796","post","type-post","status-publish","format-gallery","hentry","category-noticias","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":4,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts\/1796\/revisions"}],"predecessor-version":[{"id":1801,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts\/1796\/revisions\/1801"}],"wp:attachment":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/categories?post=1796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/tags?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}