{"id":4857,"date":"2017-02-10T14:05:44","date_gmt":"2017-02-10T18:35:44","guid":{"rendered":"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/?p=4857"},"modified":"2017-02-10T14:05:44","modified_gmt":"2017-02-10T18:35:44","slug":"daccs-sostuvo-reunion-con-representante-de-la-oac-del-ministerio-del-poder-popular-para-la-cultura","status":"publish","type":"post","link":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/2017\/02\/daccs-sostuvo-reunion-con-representante-de-la-oac-del-ministerio-del-poder-popular-para-la-cultura\/","title":{"rendered":"DACCS sostuvo reuni\u00f3n con representante de la OAC del Ministerio del Poder Popular para la Cultura"},"content":{"rendered":"<p>Consolidando el PESNCF 2016-2021<\/p>\n<p><strong>\u00a0DACCS sostuvo reuni\u00f3n con representante de la OAC del Ministerio del Poder Popular para la Cultura<\/strong><\/p>\n<p><strong>\u00a0<\/strong><em>\u201cPr\u00f3ximamente estaremos reunidos con representantes de otras Oficinas de Atenci\u00f3n al Ciudadano de la Administraci\u00f3n P\u00fablica\u201d, explic\u00f3 Ad\u00e1n Poleo, director de la DACCS de la CGR<\/em><\/p>\n<p style=\"text-align: justify;\">El equipo de trabajo de la Direcci\u00f3n de Atenci\u00f3n al Ciudadano y Control Social (DACCS) de la Contralor\u00eda General de la Rep\u00fablica Bolivariana de Venezuela sostuvo una mesa de trabajo con un representante del Ministerio del Poder Popular para la Cultura, a fin de unificar criterios institucionales en el funcionamiento de las Oficinas de Atenci\u00f3n al Ciudadano (OAC) de la Administraci\u00f3n P\u00fablica. Adem\u00e1s, estos encuentros fortalecen la participaci\u00f3n ciudadana a trav\u00e9s de las quejas, denuncias, reclamos, sugerencias y peticiones.<\/p>\n<p style=\"text-align: justify;\">En esta ocasi\u00f3n, el director de la DACCS, Ad\u00e1n Poleo, manifest\u00f3 que este a\u00f1o 2017 la direcci\u00f3n est\u00e1 activando mediante la Unidad de Informaci\u00f3n y Promoci\u00f3n de la Participaci\u00f3n Ciudadana y Control Social, liderada por la licenciada Andre\u00edna Barrios, el fortalecimiento de la participaci\u00f3n activa y protag\u00f3nica del poder popular, para cumplir con el objetivo n\u00famero 4 del Plan Estrat\u00e9gico del Sistema Nacional de Control Fiscal 2016-2021, el cual reactiva los valores y principios indispensables en la ciudadan\u00eda y que \u201choy en d\u00eda se necesitan rescatar y reforzar\u201d. Asimismo, mencion\u00f3: \u201cEstamos fortaleciendo la educaci\u00f3n para prevenir la corrupci\u00f3n, como lo expresa el ciudadano contralor general de la Rep\u00fablica Bolivariana de Venezuela, Dr. Manuel Enrique Galindo Ballesteros, en su lema\u201d.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el representante de la Oficina de Atenci\u00f3n al Ciudadano del Ministerio del Poder Popular para la Cultura, Daniel Pe\u00f1a, coment\u00f3 que la reuni\u00f3n permiti\u00f3 estrechar lazos interinstitucionales y solicitar capacitaci\u00f3n para el personal de la OAC del ministerio y de sus entes adscritos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2017\/02\/2-M-A.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4858 aligncenter\" src=\"http:\/\/www.contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2017\/02\/2-M-A-300x225.jpg\" alt=\"2 M-A\" width=\"300\" height=\"225\" srcset=\"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2017\/02\/2-M-A-300x225.jpg 300w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2017\/02\/2-M-A-768x576.jpg 768w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2017\/02\/2-M-A-1024x768.jpg 1024w, https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-content\/uploads\/2017\/02\/2-M-A.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consolidando el PESNCF 2016-2021 \u00a0DACCS sostuvo reuni\u00f3n con representante de la OAC del Ministerio del Poder Popular para la Cultura \u00a0\u201cPr\u00f3ximamente estaremos reunidos con representantes de otras Oficinas de Atenci\u00f3n al Ciudadano de la Administraci\u00f3n P\u00fablica\u201d, explic\u00f3 Ad\u00e1n Poleo, director &hellip; <a class=\"more-link\" href=\"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/2017\/02\/daccs-sostuvo-reunion-con-representante-de-la-oac-del-ministerio-del-poder-popular-para-la-cultura\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-4857","post","type-post","status-publish","format-gallery","hentry","category-noticias-cgr","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts\/4857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/comments?post=4857"}],"version-history":[{"count":1,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts\/4857\/revisions"}],"predecessor-version":[{"id":4859,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/posts\/4857\/revisions\/4859"}],"wp:attachment":[{"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/media?parent=4857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/categories?post=4857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contraloriaestadoamazonas.gob.ve\/amz\/wp-json\/wp\/v2\/tags?post=4857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}